{"id":242,"date":"2025-07-15T22:14:26","date_gmt":"2025-07-15T20:14:26","guid":{"rendered":"https:\/\/great-villani.92-205-165-115.plesk.page\/?page_id=242"},"modified":"2026-01-23T11:26:03","modified_gmt":"2026-01-23T10:26:03","slug":"post-editing","status":"publish","type":"page","link":"https:\/\/www.diction.ch\/en\/how-we-work\/create\/post-editing\/","title":{"rendered":"Post-editing"},"content":{"rendered":"<h1>Post-Editing<\/h1>\n<h2>Sind KI-\u00dcbersetzungen ohne Bearbeitung gut genug?<\/h2>\n<div>\n<p>Das kommt nat\u00fcrlich immer auf deine Erwartungen an, aber wer mit seiner Zielgruppe professionell und ungek\u00fcnstelt kommunizieren m\u00f6chte, setzt auf die Kombi KI-\u00dcbersetzungen mit Post-Editing. Dabei checkt ein menschlicher (Linguisten-)Verstand noch einmal, was das Maschinengehirn geschaffen hat.<\/p>\n<\/div>\n<h2>Wie funktioniert das Post-Editing?<\/h2>\n<div>\n<p style=\"text-align: center;\">Ganz einfach in ein paar effektiven Schritten: Der von AI \u00fcbersetzte Text wird von unseren Expertinnen und Experten auf inhaltliche, grammatikalische sowie (je nach Wunsch) auch auf stilistische Ungereimtheiten durchgecheckt. Dieser Mittelweg mit sowohl Mensch als auch Maschine sorgt daf\u00fcr, dass deine \u00dcbersetzung diesen unnachahmlichen human-gepr\u00fcften Touch bekommt, und du doch viel Zeit und Kosten sparst.<\/p>\n<\/div>\n<h2>Wir sind dein Partner<\/h2>\n<h3>Du hast keine Zeit, dich um Sprachl\u00f6sungen zu k\u00fcmmern? Wir umso mehr!<\/h3>\n<div>\n<p>Wie kann ich langfristig \u00dcbersetzungskosten senken und Prozesse vereinfachen? \u2013 Das fragst du dich, hast aber keine Zeit, dich in die Materie einzulesen? Gerne beraten wir dich kostenlos und unverbindlich. Post-Editing ist nur einer unserer Services, mit denen wir Workflows streamlinen und Top-Sprachqualit\u00e4t sichern. Melde dich einfach!<\/p>\n<\/div>\n<p><p>\n        <a href=\"https:\/\/meetings-eu1.hubspot.com\/adrian-haefelin\/beratung-demo\">Wir beraten dich kostenlos<\/a>\n    <\/p>\n<\/p>\n<hr>\n<h2>Wozu braucht man Post-Editing?<\/h2>\n<div>\n<p>Um Zeit und Kosten zu sparen! Denn: AI ist (meistens) ja sch\u00f6n und gut, doch ganz sauber wird der maschinelle Output auch heute noch nicht. Es gibt weiterhin typische Fehler \u2013 manchmal sind sie sofort ersichtlich, manchmal wirklich t\u00fcckisch \u2013, und diese Fehler werden beim Post-Editing korrigiert. Auf diese Weise erh\u00e4ltst du viel bessere Resultate, Texte, die sich wie eine Human\u00fcbersetzung lesen, ohne dass du zu viel Zeit oder Ressourcen investieren musst. Auf was sollte man beim Post-Editing achten? Wenn du einen Anbieter f\u00fcrs Post-Editing suchst, solltest du sichergehen, dass die Agentur oder die Person auch nach ISO 18587 zertifiziert ist.<\/p>\n<p>Kann es sein, dass du maschinell \u00fcbersetzen l\u00e4sst und kein Post-Editing brauchst? Ja, wenn deine Anspr\u00fcche an den \u00fcbersetzten Text nicht so hoch sind und du nur die Basics verstehen willst. Oder wenn du eine mit deiner Unternehmensterminologie sehr gut trainierte Maschine nutzt, deren Ergebnisse du verl\u00e4sslich findest. In jedem anderen Fall empfehlen wir dir aber, es nicht bei der maschinellen Roh\u00fcbersetzung zu belassen, sondern ein Post-Editing durch Profi-Linguistinnen anzuh\u00e4ngen. Deine Kosten bleiben dennoch niedriger als bei einer Human\u00fcbersetzung.<\/p>\n<\/div>\n<div>\n<p>Auf was sollte man beim Post-Editing achten? Wenn du einen Anbieter f\u00fcrs Post-Editing suchst, solltest du sichergehen, dass die Agentur oder die Person auch nach ISO 18587 zertifiziert ist. So wie Diction! Diese ISO-Norm stellt sicher, dass wir nur qualifizierte \u00dcbersetzer einsetzen, die sich auf dem Gebiet weiterbilden und auskennen. Zudem legt die Norm genau fest, welche Leistungen ein Full-Post-Editing (mehr Eingriffe) und ein Light-Post-Editing (weniger Eingriffe) umfasst. Ohne die Zertifizierung k\u00f6nnte unklar sein, was alles zum Post-Editing geh\u00f6rt und wie es konkret abl\u00e4uft. Erfahre <a href=\"\/trust-center\/\" target=\"_blank\" style=\"text-decoration:underline;\">hier<\/a><br \/>\n mehr \u00fcber die ISO 18587 und unsere anderen Zertifizierungen.<\/p>\n<p>Und apropos Zertifizierungen. Auch mit der ISO 27001 f\u00fcr Informationssicherheit sind wir voll ger\u00fcstet \u2013 f\u00fcr eure sensiblen Dokumente. Doch Vorsicht: Wenn ihr eure Texte vor dem Post-Editing selbst mit Hilfe einer \u00f6ffentlich verf\u00fcgbaren Translation-Plattform \u00fcbersetzt, k\u00f6nnte der Datenschutz je nachdem, wo der Server sitzt, euren Anspr\u00fcchen vielleicht nicht gen\u00fcgen. Zum Beispiel, wenn bestimmte Informationen den Schweizer Datenraum nicht verlassen d\u00fcrfen.<\/p>\n<p>Aber das kl\u00e4ren wir gemeinsam, ruf uns einfach an!<\/p>\n<\/div>\n<h2>Expertin<\/h2>\n<h3>Du brauchst Unterst\u00fctzung? Wir sind f\u00fcr dich da!<\/h3>\n<div>\n<p>M\u00f6chtest du mehr \u00fcber die M\u00f6glichkeiten des Post-Editing erfahren? Gerne beraten wir dich und helfen dir mit der besten L\u00f6sung weiter. C\u00e9line Rodriguez Barbur freut sich \u00fcber einen Anruf oder eine E-Mail, wenn du zum Post-Editing Fragen hast.<\/p>\n<p><a href=\"mailto:beratung@diction.ch\">beratung@diction.ch<\/a><br \/><a href=\"tel:+41817505333\">+41 81 750 53 33\u00a0<\/a><\/p>\n<\/div>\n<p><img decoding=\"async\" src=\"\/wp-content\/uploads\/2025\/12\/00_diction_Celine-Rodriguez-Barbur.jpg\" alt=\"\"><\/p>\n<h2>Was ist der Unterschied zwischen Full-Post-Editing und Light-Post-Editing?<\/h2>\n<div>\n<p>Es bedeutet, dass wir dir genau die Menge an Nachkorrektur anbieten, die du brauchst. Es gibt sehr viele verschiedene Systeme zur KI-\u00dcbersetzung, die alle ein wenig unterschiedliche Resultate liefern. Je nach Output muss das Post-Editing mehr oder weniger intensiv durchgef\u00fchrt werden. Bei unserem Angebot halten wir uns mindestens an den in der Norm ISO 18587 festgelegten Leistungskatalog oder gehen sogar dar\u00fcber hinaus. Gerne richten wir uns aber auch nach deinen individuellen W\u00fcnschen und Bed\u00fcrfnissen. Wir bieten Post-Editing in all unseren Sprachen und f\u00fcr verschiedene Branchen.<\/p>\n<p>Wie kannst du dein Leistungspaket f\u00fcr KI-\u00dcbersetzung mit Post-Editing individuell zusammenstellen? Einfach kurz anrufen oder schreiben! Gemeinsam finden wir die optimale L\u00f6sung f\u00fcr dein Projekt.<\/p>\n<\/div>\n<ul>\n<li>\n<h3>Light-Post-Editing<\/h3>\n<div>\n<p>Ziel ist ein verst\u00e4ndlicher und inhaltlich korrekter Text, ohne grosse Qualit\u00e4tsanspr\u00fcche beim Stil. Hier wird nur bei echten Grammatik- oder Rechtschreibfehlern eingegriffen oder wenn der Zieltext sonst nicht verst\u00e4ndlich w\u00e4re. Inhaltliche Fehler werden immer korrigiert.<\/p>\n<\/div>\n<\/li>\n<li>\n<h3>Ist Light-Post-Editing das Richtige f\u00fcr dich?<\/h3>\n<div>\n<p>Die \u201eleichte\u201c Option gen\u00fcgt, wenn dein Text korrekt und verst\u00e4ndlich sein soll, deine Zielgruppe aber keinen superfl\u00fcssigen, absolut stilsicheren Text erwartet. Das k\u00f6nnte zum Beispiel f\u00fcr interne Kommunikation gelten.<\/p>\n<\/div>\n<\/li>\n<li>\n<h3>Full-Post-Editing<\/h3>\n<div>\n<p>Beim Full-Post-Editing wird der maschinelle Output so editiert, dass sich das Resultat qualitativ einer Human\u00fcbersetzung ann\u00e4hert. Dazu geh\u00f6rt das Pr\u00fcfen von Rechtschreibung, Grammatik, Syntax und Zeichensetzung. Zudem richten wir uns nach eurer Terminologie und eurem Styleguide.<\/p>\n<\/div>\n<\/li>\n<li>\n<h3>Ist Full-Post-Editing das Richtige f\u00fcr dich?<\/h3>\n<div>\n<p>Wenn der Text ver\u00f6ffentlicht werden soll (vor allem ausserhalb deines Unternehmens) und er sich wirklich perfekt und fl\u00fcssig lesen soll, profitierst du von dieser Variante.<\/p>\n<\/div>\n<\/li>\n<\/ul>\n<h2>Wie stellen wir optimales Post-Editing sicher? Wir bilden uns weiter!<\/h2>\n<div>\n<p>Die Norm ISO 18587 besagt ja, dass wir nur qualifizierte \u00dcbersetzerinnen und \u00dcbersetzer einsetzen, die sich in Bezug auf Post-Editing auch weiterbilden. In diesem Zusammenhang hat Diction gemeinsam mit der ZHAW Z\u00fcrcher Hochschule f\u00fcr Angewandte Wissenschaften ein Intensivtraining im Post-Editing entwickelt, mit dem unsere Profis immer wieder dazulernen und technisch sowie handwerklich auf dem Laufenden bleiben.<\/p>\n<\/div>\n<div>\n<p>    <script type=\"application\/ld+json\">\n{\n  \"@context\": \"https:\/\/schema.org\",\n  \"@type\": \"FAQPage\",\n  \"mainEntity\": [{\n    \"@type\": \"Question\",\n    \"name\": \"Sind KI-\u00dcbersetzungen ohne Bearbeitung gut genug?\",\n    \"acceptedAnswer\": {\n      \"@type\": \"Answer\",\n      \"text\": \"Das kommt nat\u00fcrlich immer auf deine Erwartungen an, aber wer mit seiner Zielgruppe professionell und ungek\u00fcnstelt kommunizieren m\u00f6chte, setzt auf die Kombi KI-\u00dcbersetzungen mit Post-Editing. Dabei checkt ein menschlicher (Linguisten-)Verstand noch einmal, was das Maschinengehirn geschaffen hat.\"\n    }\n  },{\n    \"@type\": \"Question\",\n    \"name\": \"Wie funktioniert das Post-Editing?\",\n    \"acceptedAnswer\": {\n      \"@type\": \"Answer\",\n      \"text\": \"Ganz einfach in ein paar effektiven Schritten: Der von AI \u00fcbersetzte Text wird von unseren Expertinnen und Experten auf inhaltliche, grammatikalische sowie (je nach Wunsch) auch auf stilistische Ungereimtheiten durchgecheckt. Dieser Mittelweg mit sowohl Mensch als auch Maschine sorgt daf\u00fcr, dass deine \u00dcbersetzung diesen unnachahmlichen human-gepr\u00fcften Touch bekommt, und du doch viel Zeit und Kosten sparst.\"\n    }\n  },{\n    \"@type\": \"Question\",\n    \"name\": \"Wozu braucht man Post-Editing?\",\n    \"acceptedAnswer\": {\n      \"@type\": \"Answer\",\n      \"text\": \"Um Zeit und Kosten zu sparen! Denn: AI ist (meistens) ja sch\u00f6n und gut, doch ganz sauber wird der maschinelle Output auch heute noch nicht. Es gibt weiterhin typische Fehler \u2013 manchmal sind sie sofort ersichtlich, manchmal wirklich t\u00fcckisch \u2013, und diese Fehler werden beim Post-Editing korrigiert. Auf diese Weise erh\u00e4ltst du viel bessere Resultate, Texte, die sich wie eine Human\u00fcbersetzung lesen, ohne dass du zu viel Zeit oder Ressourcen investieren musst. Auf was sollte man beim Post-Editing achten? Wenn du einen Anbieter f\u00fcrs Post-Editing suchst, solltest du sichergehen, dass die Agentur oder die Person auch nach ISO 18587 zertifiziert ist.\nKann es sein, dass du maschinell \u00fcbersetzen l\u00e4sst und kein Post-Editing brauchst? Ja, wenn deine Anspr\u00fcche an den \u00fcbersetzten Text nicht so hoch sind und du nur die Basics verstehen willst. Oder wenn du eine mit deiner Unternehmensterminologie sehr gut trainierte Maschine nutzt, deren Ergebnisse du verl\u00e4sslich findest. In jedem anderen Fall empfehlen wir dir aber, es nicht bei der maschinellen Roh\u00fcbersetzung zu belassen, sondern ein Post-Editing durch Profi-Linguistinnen anzuh\u00e4ngen. Deine Kosten bleiben dennoch niedriger als bei einer Human\u00fcbersetzung.<\/p>\n<p>Auf was sollte man beim Post-Editing achten? Wenn du einen Anbieter f\u00fcrs Post-Editing suchst, solltest du sichergehen, dass die Agentur oder die Person auch nach ISO 18587 zertifiziert ist. So wie Diction! Diese ISO-Norm stellt sicher, dass wir nur qualifizierte \u00dcbersetzer einsetzen, die sich auf dem Gebiet weiterbilden und auskennen. Zudem legt die Norm genau fest, welche Leistungen ein Full-Post-Editing (mehr Eingriffe) und ein Light-Post-Editing (weniger Eingriffe) umfasst. Ohne die Zertifizierung k\u00f6nnte unklar sein, was alles zum Post-Editing geh\u00f6rt und wie es konkret abl\u00e4uft. Erfahre hier mehr \u00fcber die ISO 18587 und unsere anderen Zertifizierungen.<\/p>\n<p>Und apropos Zertifizierungen. Auch mit der ISO 27001 f\u00fcr Informationssicherheit sind wir voll ger\u00fcstet \u2013 f\u00fcr eure sensiblen Dokumente. Doch Vorsicht: Wenn ihr eure Texte vor dem Post-Editing selbst mit Hilfe einer \u00f6ffentlich verf\u00fcgbaren Translation-Plattform \u00fcbersetzt, k\u00f6nnte der Datenschutz je nachdem, wo der Server sitzt, euren Anspr\u00fcchen vielleicht nicht gen\u00fcgen. Zum Beispiel, wenn bestimmte Informationen den Schweizer Datenraum nicht verlassen d\u00fcrfen.\"\n    }\n  },{\n    \"@type\": \"Question\",\n    \"name\": \"Was ist der Unterschied zwischen Full-Post-Editing und Light-Post-Editing?\",\n    \"acceptedAnswer\": {\n      \"@type\": \"Answer\",\n      \"text\": \"Es bedeutet, dass wir dir genau die Menge an Nachkorrektur anbieten, die du brauchst. Es gibt sehr viele verschiedene Systeme zur KI-\u00dcbersetzung, die alle ein wenig unterschiedliche Resultate liefern. Je nach Output muss das Post-Editing mehr oder weniger intensiv durchgef\u00fchrt werden. Bei unserem Angebot halten wir uns mindestens an den in der Norm ISO 18587 festgelegten Leistungskatalog oder gehen sogar dar\u00fcber hinaus. Gerne richten wir uns aber auch nach deinen individuellen W\u00fcnschen und Bed\u00fcrfnissen. Wir bieten Post-Editing in all unseren Sprachen und f\u00fcr verschiedene Branchen.\"\n    }\n  }]\n}\n<\/script>\n<\/div>\n<p><!--more--><br \/>\n<!-- {\"type\":\"layout\",\"children\":[{\"type\":\"section\",\"props\":{\"image_position\":\"center-center\",\"style\":\"default\",\"title_breakpoint\":\"xl\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"vertical_align\":\"middle\",\"width\":\"default\"},\"children\":[{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\"},\"children\":[{\"type\":\"headline\",\"props\":{\"content\":\"Post-Editing\",\"content_en_us\":\"Post-editing\",\"css\":\".el-element {\\ntext-transform:uppercase;\\n    font-size:20px;\\n    font-weight:400;\\n}\",\"text_align\":\"center\",\"title_color\":\"primary\",\"title_element\":\"h1\"}},{\"type\":\"headline\",\"props\":{\"content\":\"Sind KI-\\u00dcbersetzungen ohne Bearbeitung gut genug?\",\"content_en_us\":\"Are AI translations good enough without editing?\",\"css\":\".el-element {\\ntext-transform:uppercase;\\n    font-size:32px;\\n}\",\"margin_remove_top\":true,\"text_align\":\"center\",\"title_element\":\"h2\"}},{\"type\":\"text\",\"props\":{\"column_breakpoint\":\"m\",\"content\":\"\n\n<p>Das kommt nat\\u00fcrlich immer auf deine Erwartungen an, aber wer mit seiner Zielgruppe professionell und ungek\\u00fcnstelt kommunizieren m\\u00f6chte, setzt auf die Kombi KI-\\u00dcbersetzungen mit Post-Editing. Dabei checkt ein menschlicher (Linguisten-)Verstand noch einmal, was das Maschinengehirn geschaffen hat.<\\\/p>\",\"content_en_us\":\"Of course, it always depends on your expectations, but if you want to communicate with your target audience in a professional and natural way, you should opt to combine AI translations and post-editing. During the post-editing, a linguist checks the machine output.\",\"css\":\".el-element {\\nfont-size:20px;\\n}\",\"margin\":\"default\",\"text_align\":\"center\"}}]}]}]},{\"type\":\"section\",\"props\":{\"image_position\":\"center-center\",\"padding\":\"large\",\"style\":\"muted\",\"title_breakpoint\":\"xl\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"vertical_align\":\"middle\",\"width\":\"default\"},\"children\":[{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"vertical_align\":\"middle\"},\"children\":[{\"type\":\"headline\",\"props\":{\"content\":\"Wie funktioniert das Post-Editing?\",\"content_en_us\":\"How does post-editing work?\",\"css\":\".el-element {\\ntext-transform:uppercase;\\n    font-size:32px;\\n}\",\"margin_remove_top\":true,\"text_align\":\"center\",\"title_element\":\"h2\"}}]}]},{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\"},\"children\":[{\"type\":\"text\",\"props\":{\"column_breakpoint\":\"m\",\"content\":\"\n\n<p style=\\\"text-align: center;\\\">Ganz einfach in ein paar effektiven Schritten: Der von AI \\u00fcbersetzte Text wird von unseren Expertinnen und Experten auf inhaltliche, grammatikalische sowie (je nach Wunsch) auch auf stilistische Ungereimtheiten durchgecheckt. Dieser Mittelweg mit sowohl Mensch als auch Maschine sorgt daf\\u00fcr, dass deine \\u00dcbersetzung diesen unnachahmlichen human-gepr\\u00fcften Touch bekommt, und du doch viel Zeit und Kosten sparst.<\\\/p>\",\"content_en_us\":\"The text translated by AI is checked by our experts for content, grammar and (if desired) stylistic inconsistencies. This process, including both humans and machines, ensures that your translation reads like an original, while still saving you a lot of time and money.\",\"css\":\".el-element {\\nfont-size:20px !important;\\n}\\n\\n.el-element h3 {\\nfont-size:25px !important;\\n}\",\"margin\":\"default\"}}]}]}]},{\"type\":\"section\",\"props\":{\"image_position\":\"center-center\",\"style\":\"secondary\",\"title_breakpoint\":\"xl\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"vertical_align\":\"middle\",\"width\":\"default\"},\"children\":[{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\"},\"children\":[{\"type\":\"headline\",\"props\":{\"content\":\"Wir sind dein Partner\",\"content_en_us\":\"We are your partner\",\"css\":\".el-element {\\ntext-transform:uppercase;\\n    font-size:20px;\\n    font-weight:400;\\n}\",\"title_color\":\"primary\",\"title_element\":\"h2\"}},{\"type\":\"headline\",\"props\":{\"content\":\"Du hast keine Zeit, dich um Sprachl\\u00f6sungen zu k\\u00fcmmern? Wir umso mehr!\",\"content_en_us\":\"Don\\u2019t have time to think about language solutions? We certainly do!\",\"css\":\".el-element {\\ntext-transform:uppercase;\\n    font-size:32px;\\n}\",\"margin_remove_top\":true,\"title_element\":\"h3\"}},{\"type\":\"text\",\"props\":{\"column_breakpoint\":\"m\",\"content\":\"\n\n<p>Wie kann ich langfristig \\u00dcbersetzungskosten senken und Prozesse vereinfachen? \\u2013 Das fragst du dich, hast aber keine Zeit, dich in die Materie einzulesen? Gerne beraten wir dich kostenlos und unverbindlich. Post-Editing ist nur einer unserer Services, mit denen wir Workflows streamlinen und Top-Sprachqualit\\u00e4t sichern. Melde dich einfach!<\\\/p>\",\"content_en_us\":\"How can you reduce translation costs and simplify processes in the long term? We\\u2019ll gladly advise you free of charge and with no obligation. Post-editing is just one of the services we offer to streamline workflows and ensure top-quality language services. Get in touch today!\",\"css\":\".el-element {\\nfont-size:20px !important;\\n}\\n\\n.el-element h3 {\\nfont-size:25px !important;\\n}\",\"margin\":\"default\"}},{\"type\":\"button\",\"props\":{\"css\":\".el-content {\\nfont-size:20px;\\npadding:10px 25px;\\n    font-weight:300 !important;\\nbackground:#fff;\\n    color:#000;\\n}\\n\\n\\n@media only screen and (max-width: 600px) {\\n.el-content {\\n    font-size:17px !important;\\n    padding:10px 15px !important;\\n}\\n}\",\"grid_column_gap\":\"small\",\"grid_row_gap\":\"small\",\"margin\":\"default\"},\"children\":[{\"type\":\"button_item\",\"props\":{\"button_style\":\"default\",\"content\":\"Wir beraten dich kostenlos\",\"content_en_us\":\"Get your free consultation now\",\"dialog_layout\":\"modal\",\"dialog_offcanvas_flip\":true,\"icon_align\":\"left\",\"link\":\"https:\\\/\\\/meetings-eu1.hubspot.com\\\/adrian-haefelin\\\/beratung-demo\",\"link_target\":\"blank\"}}]}]}]}]},{\"type\":\"section\",\"props\":{\"image_position\":\"center-center\",\"padding\":\"large\",\"style\":\"default\",\"title_breakpoint\":\"xl\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"vertical_align\":\"middle\",\"width\":\"default\"},\"children\":[{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"vertical_align\":\"middle\"},\"children\":[{\"type\":\"divider\",\"props\":{\"divider_align\":\"center\",\"divider_element\":\"hr\",\"divider_style\":\"small\"}},{\"type\":\"headline\",\"props\":{\"content\":\"Wozu braucht man Post-Editing?\",\"content_en_us\":\"Why is post-editing useful?\",\"css\":\".el-element {\\ntext-transform:uppercase;\\n    font-size:32px;\\n}\",\"margin_remove_top\":true,\"text_align\":\"center\",\"title_element\":\"h2\"}}]}]},{\"type\":\"row\",\"props\":{\"layout\":\"1-2,1-2\"},\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"width_medium\":\"1-2\"},\"children\":[{\"type\":\"text\",\"props\":{\"column_breakpoint\":\"m\",\"content\":\"\n\n<p>Um Zeit und Kosten zu sparen! Denn: AI ist (meistens) ja sch\\u00f6n und gut, doch ganz sauber wird der maschinelle Output auch heute noch nicht. Es gibt weiterhin typische Fehler \\u2013 manchmal sind sie sofort ersichtlich, manchmal wirklich t\\u00fcckisch \\u2013, und diese Fehler werden beim Post-Editing korrigiert. Auf diese Weise erh\\u00e4ltst du viel bessere Resultate, Texte, die sich wie eine Human\\u00fcbersetzung lesen, ohne dass du zu viel Zeit oder Ressourcen investieren musst. Auf was sollte man beim Post-Editing achten? Wenn du einen Anbieter f\\u00fcrs Post-Editing suchst, solltest du sichergehen, dass die Agentur oder die Person auch nach ISO 18587 zertifiziert ist.<\\\/p>\\n\n\n<p>Kann es sein, dass du maschinell \\u00fcbersetzen l\\u00e4sst und kein Post-Editing brauchst? Ja, wenn deine Anspr\\u00fcche an den \\u00fcbersetzten Text nicht so hoch sind und du nur die Basics verstehen willst. Oder wenn du eine mit deiner Unternehmensterminologie sehr gut trainierte Maschine nutzt, deren Ergebnisse du verl\\u00e4sslich findest. In jedem anderen Fall empfehlen wir dir aber, es nicht bei der maschinellen Roh\\u00fcbersetzung zu belassen, sondern ein Post-Editing durch Profi-Linguistinnen anzuh\\u00e4ngen. Deine Kosten bleiben dennoch niedriger als bei einer Human\\u00fcbersetzung.<\\\/p>\",\"content_en_us\":\"\n\n<p>To save you time, money and stress. AI delivers good results, but the results are not flawless. Some typical errors are easy to spot, others are more subtle \\u2013 and that\\u2019s exactly where post-editing comes in. This step ensures significantly higher quality: texts that read like human translations, without requiring excessive time or resources.<\\\/p>\\n\n\n<p>Is it possible to use AI translation without post-editing? It is, if your expectations with regards to quality are not too high, and you just want to understand the basics. Or if you use a machine that is very well trained with your company\\u2019s terminology and whose results you find reliable. For all other texts, we recommend having your machine output checked by an expert in order to ensure accuracy. This will still save you money in comparison to a standard translation.<\\\/p>\",\"css\":\".el-element {\\nfont-size:20px !important;\\n}\\n\\n.el-element h3 {\\nfont-size:25px !important;\\n}\",\"margin\":\"default\"}}]},{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"width_medium\":\"1-2\"},\"children\":[{\"type\":\"text\",\"props\":{\"column_breakpoint\":\"m\",\"content\":\"\n\n<p>Auf was sollte man beim Post-Editing achten? Wenn du einen Anbieter f\\u00fcrs Post-Editing suchst, solltest du sichergehen, dass die Agentur oder die Person auch nach ISO 18587 zertifiziert ist. So wie Diction! Diese ISO-Norm stellt sicher, dass wir nur qualifizierte \\u00dcbersetzer einsetzen, die sich auf dem Gebiet weiterbilden und auskennen. Zudem legt die Norm genau fest, welche Leistungen ein Full-Post-Editing (mehr Eingriffe) und ein Light-Post-Editing (weniger Eingriffe) umfasst. Ohne die Zertifizierung k\\u00f6nnte unklar sein, was alles zum Post-Editing geh\\u00f6rt und wie es konkret abl\\u00e4uft. Erfahre <a href=\\\"trust-center\\\/\\\" target=\\\"_blank\\\" style=\\\"text-decoration:underline;\\\">hier<\\\/a>\\n mehr \\u00fcber die ISO 18587 und unsere anderen Zertifizierungen.<\\\/p>\\n\n\n<p>Und apropos Zertifizierungen. Auch mit der ISO 27001 f\\u00fcr Informationssicherheit sind wir voll ger\\u00fcstet \\u2013 f\\u00fcr eure sensiblen Dokumente. Doch Vorsicht: Wenn ihr eure Texte vor dem Post-Editing selbst mit Hilfe einer \\u00f6ffentlich verf\\u00fcgbaren Translation-Plattform \\u00fcbersetzt, k\\u00f6nnte der Datenschutz je nachdem, wo der Server sitzt, euren Anspr\\u00fcchen vielleicht nicht gen\\u00fcgen. Zum Beispiel, wenn bestimmte Informationen den Schweizer Datenraum nicht verlassen d\\u00fcrfen.<\\\/p>\\n\n\n<p>Aber das kl\\u00e4ren wir gemeinsam, ruf uns einfach an!<\\\/p>\",\"content_en_us\":\"\n\n<p>If you are looking for a post-editing provider, you should ensure that the agency is certified according to ISO 18587 (as Diction is, of course). This ISO standard ensures that we only use qualified translators who are trained and knowledgeable in their field. It also determines which services are included in full and light post-editing. If you choose a provider without the ISO certification, the conditions of service could be unclear. Click here to find out more about ISO 18587 and our other certifications.<\\\/p>\\n\n\n<p>Speaking of certifications: our ISO 27001 certifications confirms that your sensitive data is protected according to the highest information security standards. A quick word of caution: if you translate texts yourself using a public online translation platform before post-editing, data protection requirements may not be met, depending on where the server is located.<\\\/p>\\n\n\n<p>Interested? Give us a call today to discuss the different options.<\\\/p>\",\"css\":\".el-element {\\nfont-size:20px !important;\\n}\\n\\n.el-element h3 {\\nfont-size:25px !important;\\n}\",\"margin\":\"default\"}}]}]}]},{\"type\":\"section\",\"props\":{\"image_position\":\"center-center\",\"style\":\"secondary\",\"title_breakpoint\":\"xl\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"vertical_align\":\"middle\",\"width\":\"default\"},\"children\":[{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"width_medium\":\"3-5\"},\"children\":[{\"type\":\"headline\",\"props\":{\"content\":\"Expertin\",\"content_en_us\":\"Expertise\",\"css\":\".el-element {\\ntext-transform:uppercase;\\n    font-size:20px;\\n    font-weight:400;\\n}\",\"title_color\":\"primary\",\"title_element\":\"h2\"}},{\"type\":\"headline\",\"props\":{\"content\":\"Du brauchst Unterst\\u00fctzung? Wir sind f\\u00fcr dich da!\",\"content_en_us\":\"Do you need assistance? We are here for you!\",\"css\":\".el-element {\\ntext-transform:uppercase;\\n    font-size:32px;\\n}\",\"margin_remove_top\":true,\"title_element\":\"h3\"}},{\"type\":\"text\",\"props\":{\"column_breakpoint\":\"m\",\"content\":\"\n\n<p>M\\u00f6chtest du mehr \\u00fcber die M\\u00f6glichkeiten des Post-Editing erfahren? Gerne beraten wir dich und helfen dir mit der besten L\\u00f6sung weiter. C\\u00e9line Rodriguez Barbur freut sich \\u00fcber einen Anruf oder eine E-Mail, wenn du zum Post-Editing Fragen hast.<\\\/p>\\n\n\n<p><a href=\\\"mailto:beratung@diction.ch\\\">beratung@diction.ch<\\\/a><br \\\/><a href=\\\"tel:+41817505333\\\">+41 81 750 53 33\\u00a0<\\\/a><\\\/p>\",\"content_en_us\":\"\n\n<p>Would you like to learn more about the possibilities of post-editing? We\\u2019re happy to advise you and help you find the best solution. C\\u00e9line Rodriguez Barbur\\u00a0is happy to receive your call or email if you have any questions about post-editing.<\\\/p>\\n\n\n<p>beratung@diction.ch<br \\\/>+41 81 750 53 33<\\\/p>\\n\n\n<p><\\\/p>\",\"css\":\".el-element {\\nfont-size:20px !important;\\n}\\n\\n.el-element h3 {\\nfont-size:25px !important;\\n}\",\"margin\":\"default\"}}]},{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"width_medium\":\"2-5\"},\"children\":[{\"type\":\"image\",\"props\":{\"image\":\"wp-content\\\/uploads\\\/2025\\\/12\\\/00_diction_Celine-Rodriguez-Barbur.jpg\",\"image_svg_color\":\"emphasis\",\"margin\":\"default\"}}]}],\"props\":{\"layout\":\"3-5,2-5\"}}],\"name\":\"K01_Kasten lila Experte\"},{\"type\":\"section\",\"props\":{\"css\":\".el-section {\\nbackground:#87C7A5;\\n}\",\"image_position\":\"center-center\",\"padding\":\"large\",\"style\":\"default\",\"title_breakpoint\":\"xl\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"vertical_align\":\"middle\",\"width\":\"default\"},\"children\":[{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"vertical_align\":\"middle\"},\"children\":[{\"type\":\"headline\",\"props\":{\"content\":\"Was ist der Unterschied zwischen Full-Post-Editing und Light-Post-Editing?\",\"content_en_us\":\"What is the difference between full and light post-editing?\",\"css\":\".el-element {\\n    font-size:32px;\\n}\",\"margin_remove_top\":true,\"text_align\":\"center\",\"title_element\":\"h2\"}}]}]},{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\"},\"children\":[{\"type\":\"text\",\"props\":{\"column_breakpoint\":\"m\",\"content\":\"\n\n<p>Es bedeutet, dass wir dir genau die Menge an Nachkorrektur anbieten, die du brauchst. Es gibt sehr viele verschiedene Systeme zur KI-\\u00dcbersetzung, die alle ein wenig unterschiedliche Resultate liefern. Je nach Output muss das Post-Editing mehr oder weniger intensiv durchgef\\u00fchrt werden. Bei unserem Angebot halten wir uns mindestens an den in der Norm ISO 18587 festgelegten Leistungskatalog oder gehen sogar dar\\u00fcber hinaus. Gerne richten wir uns aber auch nach deinen individuellen W\\u00fcnschen und Bed\\u00fcrfnissen. Wir bieten Post-Editing in all unseren Sprachen und f\\u00fcr verschiedene Branchen.<\\\/p>\\n\n\n<p>Wie kannst du dein Leistungspaket f\\u00fcr KI-\\u00dcbersetzung mit Post-Editing individuell zusammenstellen? Einfach kurz anrufen oder schreiben! Gemeinsam finden wir die optimale L\\u00f6sung f\\u00fcr dein Projekt.<\\\/p>\",\"content_en_us\":\"\n\n<p>There are many different types of AI translation technology that all deliver slightly different results and may require varying amounts of work during post-editing. All of our post-editing services are in accordance with those laid out in the ISO 18587 standard or even improve upon them. Of course, we will tailor our service to meet your exact requirements. We offer post-editing services for all our languages and for different industry sectors.<\\\/p>\\n\n\n<p>To learn how you can customise your AI translation service with post-editing, call us or send us a quick email. Together, we will find the optimal solution for your project.<\\\/p>\",\"css\":\".el-element {\\nfont-size:20px !important;\\n}\\n\\n.el-element h3 {\\nfont-size:25px !important;\\n}\",\"margin\":\"default\"}}]}]},{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\"},\"children\":[{\"type\":\"grid\",\"props\":{\"content_column_breakpoint\":\"m\",\"filter_align\":\"left\",\"filter_all\":true,\"filter_grid_breakpoint\":\"m\",\"filter_grid_width\":\"auto\",\"filter_position\":\"top\",\"filter_style\":\"tab\",\"grid_default\":\"1\",\"grid_medium\":\"4\",\"grid_small\":\"2\",\"icon_width\":80,\"image_align\":\"top\",\"image_grid_breakpoint\":\"m\",\"image_grid_width\":\"1-2\",\"image_svg_color\":\"emphasis\",\"item_animation\":true,\"lightbox_bg_close\":true,\"link_style\":\"default\",\"link_text\":\"Read more\",\"margin\":\"default\",\"meta_align\":\"below-title\",\"meta_element\":\"div\",\"meta_style\":\"text-meta\",\"show_content\":true,\"show_hover_image\":true,\"show_hover_video\":true,\"show_image\":true,\"show_link\":true,\"show_meta\":true,\"show_title\":true,\"show_video\":true,\"title_align\":\"top\",\"title_element\":\"h3\",\"title_grid_breakpoint\":\"m\",\"title_grid_width\":\"1-2\",\"title_hover_style\":\"reset\"},\"children\":[{\"type\":\"grid_item\",\"props\":{\"content\":\"\n\n<p>Ziel ist ein verst\\u00e4ndlicher und inhaltlich korrekter Text, ohne grosse Qualit\\u00e4tsanspr\\u00fcche beim Stil. Hier wird nur bei echten Grammatik- oder Rechtschreibfehlern eingegriffen oder wenn der Zieltext sonst nicht verst\\u00e4ndlich w\\u00e4re. Inhaltliche Fehler werden immer korrigiert.<\\\/p>\",\"content_en_us\":\"\n\n<p>The aim is to produce a comprehensible text with accurate content, without placing great emphasis on stylistic quality. Grammar and spelling mistakes are corrected, and the text is changed if it doesn\\u2019t make sense. Content errors will always be corrected.<\\\/p>\",\"title\":\"Light-Post-Editing\",\"title_en_us\":\"Light post-editing\"}},{\"type\":\"grid_item\",\"props\":{\"content\":\"\n\n<p>Die \\u201eleichte\\u201c Option gen\\u00fcgt, wenn dein Text korrekt und verst\\u00e4ndlich sein soll, deine Zielgruppe aber keinen superfl\\u00fcssigen, absolut stilsicheren Text erwartet. Das k\\u00f6nnte zum Beispiel f\\u00fcr interne Kommunikation gelten.<\\\/p>\",\"content_en_us\":\"\n\n<p>The \\u201clight\\u201d option is sufficient if your text needs to be correct and understandable, but your target audience does not expect a super fluent, stylish text. This could apply to internal communication, for example.<\\\/p>\",\"title\":\"Ist Light-Post-Editing das Richtige f\\u00fcr dich?\",\"title_en_us\":\"Is light post-editing right for you?\"}},{\"type\":\"grid_item\",\"props\":{\"content\":\"\n\n<p>Beim Full-Post-Editing wird der maschinelle Output so editiert, dass sich das Resultat qualitativ einer Human\\u00fcbersetzung ann\\u00e4hert. Dazu geh\\u00f6rt das Pr\\u00fcfen von Rechtschreibung, Grammatik, Syntax und Zeichensetzung. Zudem richten wir uns nach eurer Terminologie und eurem Styleguide.<\\\/p>\",\"content_en_us\":\"\n\n<p>Full post-editing involves editing the machine-translated text so that the final quality is close to that of a standard translation. This includes checking spelling, grammar, syntax and punctuation. We also ensure that your terminology and style guide is used.<\\\/p>\",\"title\":\"Full-Post-Editing\",\"title_en_us\":\"Full post-editing\"}},{\"type\":\"grid_item\",\"props\":{\"content\":\"\n\n<p>Wenn der Text ver\\u00f6ffentlicht werden soll (vor allem ausserhalb deines Unternehmens) und er sich wirklich perfekt und fl\\u00fcssig lesen soll, profitierst du von dieser Variante.<\\\/p>\",\"content_en_us\":\"\n\n<p>If the text is to be published (especially outside your company) and you want it to read perfectly and fluently, you will benefit from this option.<\\\/p>\",\"title\":\"Ist Full-Post-Editing das Richtige f\\u00fcr dich?\",\"title_en_us\":\"Is full post-editing right for you?\"}}]}]}]}],\"name\":\"K01_Kasten gr\\u00fcn 4 Gl\\u00fchbirnen\"},{\"type\":\"section\",\"props\":{\"image_position\":\"center-center\",\"padding\":\"large\",\"style\":\"default\",\"title_breakpoint\":\"xl\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"vertical_align\":\"middle\",\"width\":\"default\"},\"children\":[{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"vertical_align\":\"middle\"},\"children\":[{\"type\":\"headline\",\"props\":{\"content\":\"Wie stellen wir optimales Post-Editing sicher? Wir bilden uns weiter!\",\"content_en_us\":\"How do we ensure great post-editing? With ongoing training!\",\"css\":\".el-element {\\n    font-size:32px;\\n}\",\"margin_remove_top\":true,\"text_align\":\"center\",\"title_element\":\"h2\"}}]}]},{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\"},\"children\":[{\"type\":\"text\",\"props\":{\"column_breakpoint\":\"m\",\"content\":\"\n\n<p>Die Norm ISO 18587 besagt ja, dass wir nur qualifizierte \\u00dcbersetzerinnen und \\u00dcbersetzer einsetzen, die sich in Bezug auf Post-Editing auch weiterbilden. In diesem Zusammenhang hat Diction gemeinsam mit der ZHAW Z\\u00fcrcher Hochschule f\\u00fcr Angewandte Wissenschaften ein Intensivtraining im Post-Editing entwickelt, mit dem unsere Profis immer wieder dazulernen und technisch sowie handwerklich auf dem Laufenden bleiben.<\\\/p>\",\"content_en_us\":\"\n\n<p>The ISO 18587 standard requires us to work with qualified translators who receive regular training in post-editing. To support this, Diction has teamed up with ZHAW Zurich University of Applied Sciences to develop an intensive post-editing training programme that keeps our experts up to date both technically and in day-to-day practice.<\\\/p>\",\"css\":\".el-element {\\nfont-size:20px !important;\\n}\\n\\n.el-element h3 {\\nfont-size:25px !important;\\n}\",\"margin\":\"default\"}},{\"type\":\"html\",\"props\":{\"content\":\"<script type=\\\"application\\\/ld+json\\\">\\n{\\n  \\\"@context\\\": \\\"https:\\\/\\\/schema.org\\\",\\n  \\\"@type\\\": \\\"FAQPage\\\",\\n  \\\"mainEntity\\\": [{\\n    \\\"@type\\\": \\\"Question\\\",\\n    \\\"name\\\": \\\"Sind KI-\\u00dcbersetzungen ohne Bearbeitung gut genug?\\\",\\n    \\\"acceptedAnswer\\\": {\\n      \\\"@type\\\": \\\"Answer\\\",\\n      \\\"text\\\": \\\"Das kommt nat\\u00fcrlich immer auf deine Erwartungen an, aber wer mit seiner Zielgruppe professionell und ungek\\u00fcnstelt kommunizieren m\\u00f6chte, setzt auf die Kombi KI-\\u00dcbersetzungen mit Post-Editing. Dabei checkt ein menschlicher (Linguisten-)Verstand noch einmal, was das Maschinengehirn geschaffen hat.\\\"\\n    }\\n  },{\\n    \\\"@type\\\": \\\"Question\\\",\\n    \\\"name\\\": \\\"Wie funktioniert das Post-Editing?\\\",\\n    \\\"acceptedAnswer\\\": {\\n      \\\"@type\\\": \\\"Answer\\\",\\n      \\\"text\\\": \\\"Ganz einfach in ein paar effektiven Schritten: Der von AI \\u00fcbersetzte Text wird von unseren Expertinnen und Experten auf inhaltliche, grammatikalische sowie (je nach Wunsch) auch auf stilistische Ungereimtheiten durchgecheckt. Dieser Mittelweg mit sowohl Mensch als auch Maschine sorgt daf\\u00fcr, dass deine \\u00dcbersetzung diesen unnachahmlichen human-gepr\\u00fcften Touch bekommt, und du doch viel Zeit und Kosten sparst.\\\"\\n    }\\n  },{\\n    \\\"@type\\\": \\\"Question\\\",\\n    \\\"name\\\": \\\"Wozu braucht man Post-Editing?\\\",\\n    \\\"acceptedAnswer\\\": {\\n      \\\"@type\\\": \\\"Answer\\\",\\n      \\\"text\\\": \\\"Um Zeit und Kosten zu sparen! Denn: AI ist (meistens) ja sch\\u00f6n und gut, doch ganz sauber wird der maschinelle Output auch heute noch nicht. Es gibt weiterhin typische Fehler \\u2013 manchmal sind sie sofort ersichtlich, manchmal wirklich t\\u00fcckisch \\u2013, und diese Fehler werden beim Post-Editing korrigiert. Auf diese Weise erh\\u00e4ltst du viel bessere Resultate, Texte, die sich wie eine Human\\u00fcbersetzung lesen, ohne dass du zu viel Zeit oder Ressourcen investieren musst. Auf was sollte man beim Post-Editing achten? Wenn du einen Anbieter f\\u00fcrs Post-Editing suchst, solltest du sichergehen, dass die Agentur oder die Person auch nach ISO 18587 zertifiziert ist.\\nKann es sein, dass du maschinell \\u00fcbersetzen l\\u00e4sst und kein Post-Editing brauchst? Ja, wenn deine Anspr\\u00fcche an den \\u00fcbersetzten Text nicht so hoch sind und du nur die Basics verstehen willst. Oder wenn du eine mit deiner Unternehmensterminologie sehr gut trainierte Maschine nutzt, deren Ergebnisse du verl\\u00e4sslich findest. In jedem anderen Fall empfehlen wir dir aber, es nicht bei der maschinellen Roh\\u00fcbersetzung zu belassen, sondern ein Post-Editing durch Profi-Linguistinnen anzuh\\u00e4ngen. Deine Kosten bleiben dennoch niedriger als bei einer Human\\u00fcbersetzung.\\n\\n\\nAuf was sollte man beim Post-Editing achten? Wenn du einen Anbieter f\\u00fcrs Post-Editing suchst, solltest du sichergehen, dass die Agentur oder die Person auch nach ISO 18587 zertifiziert ist. So wie Diction! Diese ISO-Norm stellt sicher, dass wir nur qualifizierte \\u00dcbersetzer einsetzen, die sich auf dem Gebiet weiterbilden und auskennen. Zudem legt die Norm genau fest, welche Leistungen ein Full-Post-Editing (mehr Eingriffe) und ein Light-Post-Editing (weniger Eingriffe) umfasst. Ohne die Zertifizierung k\\u00f6nnte unklar sein, was alles zum Post-Editing geh\\u00f6rt und wie es konkret abl\\u00e4uft. Erfahre hier mehr \\u00fcber die ISO 18587 und unsere anderen Zertifizierungen.\\n\\nUnd apropos Zertifizierungen. Auch mit der ISO 27001 f\\u00fcr Informationssicherheit sind wir voll ger\\u00fcstet \\u2013 f\\u00fcr eure sensiblen Dokumente. Doch Vorsicht: Wenn ihr eure Texte vor dem Post-Editing selbst mit Hilfe einer \\u00f6ffentlich verf\\u00fcgbaren Translation-Plattform \\u00fcbersetzt, k\\u00f6nnte der Datenschutz je nachdem, wo der Server sitzt, euren Anspr\\u00fcchen vielleicht nicht gen\\u00fcgen. Zum Beispiel, wenn bestimmte Informationen den Schweizer Datenraum nicht verlassen d\\u00fcrfen.\\\"\\n    }\\n  },{\\n    \\\"@type\\\": \\\"Question\\\",\\n    \\\"name\\\": \\\"Was ist der Unterschied zwischen Full-Post-Editing und Light-Post-Editing?\\\",\\n    \\\"acceptedAnswer\\\": {\\n      \\\"@type\\\": \\\"Answer\\\",\\n      \\\"text\\\": \\\"Es bedeutet, dass wir dir genau die Menge an Nachkorrektur anbieten, die du brauchst. Es gibt sehr viele verschiedene Systeme zur KI-\\u00dcbersetzung, die alle ein wenig unterschiedliche Resultate liefern. Je nach Output muss das Post-Editing mehr oder weniger intensiv durchgef\\u00fchrt werden. Bei unserem Angebot halten wir uns mindestens an den in der Norm ISO 18587 festgelegten Leistungskatalog oder gehen sogar dar\\u00fcber hinaus. Gerne richten wir uns aber auch nach deinen individuellen W\\u00fcnschen und Bed\\u00fcrfnissen. Wir bieten Post-Editing in all unseren Sprachen und f\\u00fcr verschiedene Branchen.\\\"\\n    }\\n  }]\\n}\\n<\\\/script>\"}}]}]}],\"name\":\"K01_Kasten weiss einspaltig mit \\u00dcberschriften\"}],\"version\":\"4.5.33\"} --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Post-Editing Sind KI-\u00dcbersetzungen ohne Bearbeitung gut genug? Das kommt nat\u00fcrlich immer auf deine Erwartungen an, aber wer mit seiner Zielgruppe professionell und ungek\u00fcnstelt kommunizieren m\u00f6chte, setzt auf die Kombi KI-\u00dcbersetzungen mit Post-Editing. Dabei checkt ein menschlicher (Linguisten-)Verstand noch einmal, was das Maschinengehirn geschaffen hat. Wie funktioniert das Post-Editing? Ganz einfach in ein paar effektiven Schritten: [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":241,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-242","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Post-editing \u2502 AI texts with human correction<\/title>\n<meta name=\"description\" content=\"During post-editing, our language experts check your text for inconsistencies in content, grammar and (if desired) style.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Post-editing \u2502 AI texts with human correction\" \/>\n<meta property=\"og:description\" content=\"During post-editing, our language experts check your text for inconsistencies in content, grammar and (if desired) style.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.diction.ch\/en\/how-we-work\/create\/post-editing\/\" \/>\n<meta property=\"og:site_name\" content=\"diction\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-23T10:26:03+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.diction.ch\\\/en\\\/how-we-work\\\/create\\\/post-editing\\\/\",\"url\":\"https:\\\/\\\/www.diction.ch\\\/en\\\/how-we-work\\\/create\\\/post-editing\\\/\",\"name\":\"Post Editing \u2502 KI-Texte mit menschlicher Korrektur\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diction.ch\\\/#website\"},\"datePublished\":\"2025-07-15T20:14:26+00:00\",\"dateModified\":\"2026-01-23T10:26:03+00:00\",\"description\":\"Unsere Sprachexperten pr\u00fcfen im Post Editing deinen Text auf inhaltliche, grammatikalische sowie (je nach Wunsch) auch auf stilistische Ungereimtheiten.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.diction.ch\\\/en\\\/how-we-work\\\/create\\\/post-editing\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.diction.ch\\\/en\\\/how-we-work\\\/create\\\/post-editing\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.diction.ch\\\/en\\\/how-we-work\\\/create\\\/post-editing\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.diction.ch\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"How we work\",\"item\":\"https:\\\/\\\/www.diction.ch\\\/so-arbeiten-wir\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Create\",\"item\":\"https:\\\/\\\/www.diction.ch\\\/so-arbeiten-wir\\\/create\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Post-editing\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.diction.ch\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.diction.ch\\\/en\\\/\",\"name\":\"diction\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.diction.ch\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.diction.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.diction.ch\\\/en\\\/#organization\",\"name\":\"diction\",\"url\":\"https:\\\/\\\/www.diction.ch\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.diction.ch\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/great-villani.92-205-165-115.plesk.page\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/diction_Logo.jpg\",\"contentUrl\":\"https:\\\/\\\/great-villani.92-205-165-115.plesk.page\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/diction_Logo.jpg\",\"width\":750,\"height\":392,\"caption\":\"diction\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diction.ch\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Post-editing \u2502 AI texts with human correction","description":"During post-editing, our language experts check your text for inconsistencies in content, grammar and (if desired) style.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"Post-editing \u2502 AI texts with human correction","og_description":"During post-editing, our language experts check your text for inconsistencies in content, grammar and (if desired) style.","og_url":"https:\/\/www.diction.ch\/en\/how-we-work\/create\/post-editing\/","og_site_name":"diction","article_modified_time":"2026-01-23T10:26:03+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.diction.ch\/en\/how-we-work\/create\/post-editing\/","url":"https:\/\/www.diction.ch\/en\/how-we-work\/create\/post-editing\/","name":"Post Editing \u2502 KI-Texte mit menschlicher Korrektur","isPartOf":{"@id":"https:\/\/www.diction.ch\/#website"},"datePublished":"2025-07-15T20:14:26+00:00","dateModified":"2026-01-23T10:26:03+00:00","description":"Unsere Sprachexperten pr\u00fcfen im Post Editing deinen Text auf inhaltliche, grammatikalische sowie (je nach Wunsch) auch auf stilistische Ungereimtheiten.","breadcrumb":{"@id":"https:\/\/www.diction.ch\/en\/how-we-work\/create\/post-editing\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.diction.ch\/en\/how-we-work\/create\/post-editing\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.diction.ch\/en\/how-we-work\/create\/post-editing\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.diction.ch\/"},{"@type":"ListItem","position":2,"name":"How we work","item":"https:\/\/www.diction.ch\/so-arbeiten-wir\/"},{"@type":"ListItem","position":3,"name":"Create","item":"https:\/\/www.diction.ch\/so-arbeiten-wir\/create\/"},{"@type":"ListItem","position":4,"name":"Post-editing"}]},{"@type":"WebSite","@id":"https:\/\/www.diction.ch\/en\/#website","url":"https:\/\/www.diction.ch\/en\/","name":"diction","description":"","publisher":{"@id":"https:\/\/www.diction.ch\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.diction.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.diction.ch\/en\/#organization","name":"diction","url":"https:\/\/www.diction.ch\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.diction.ch\/en\/#\/schema\/logo\/image\/","url":"https:\/\/great-villani.92-205-165-115.plesk.page\/wp-content\/uploads\/2025\/07\/diction_Logo.jpg","contentUrl":"https:\/\/great-villani.92-205-165-115.plesk.page\/wp-content\/uploads\/2025\/07\/diction_Logo.jpg","width":750,"height":392,"caption":"diction"},"image":{"@id":"https:\/\/www.diction.ch\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.diction.ch\/en\/wp-json\/wp\/v2\/pages\/242","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.diction.ch\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.diction.ch\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.diction.ch\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diction.ch\/en\/wp-json\/wp\/v2\/comments?post=242"}],"version-history":[{"count":27,"href":"https:\/\/www.diction.ch\/en\/wp-json\/wp\/v2\/pages\/242\/revisions"}],"predecessor-version":[{"id":2955,"href":"https:\/\/www.diction.ch\/en\/wp-json\/wp\/v2\/pages\/242\/revisions\/2955"}],"up":[{"embeddable":true,"href":"https:\/\/www.diction.ch\/en\/wp-json\/wp\/v2\/pages\/241"}],"wp:attachment":[{"href":"https:\/\/www.diction.ch\/en\/wp-json\/wp\/v2\/media?parent=242"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}